{"id":964,"date":"2017-05-23T15:06:35","date_gmt":"2017-05-23T15:06:35","guid":{"rendered":"http:\/\/productdesign.polimi.it\/?p=964"},"modified":"2017-06-22T09:03:06","modified_gmt":"2017-06-22T09:03:06","slug":"design-workshop-aziende","status":"publish","type":"news","link":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/","title":{"rendered":"Workshop come momenti di incontro tra studenti e aziende"},"content":{"rendered":"<p>Il Politecnico di Milano offre grandi opportunit\u00e0 a studenti e aziende per conoscersi e creare piccoli momenti progettuali per accrescere le proprie esperienze.<\/p>\n<p>I workshop sono laboratori intensivi sviluppati all\u2019interno di una settimana, durante la quale da un lato le aziende selezionate hanno l\u2019opportunit\u00e0 di conoscere il potenziale dei giovani designer, dall\u2019altro gli studenti possono avere un confronto diretto con gli esperti del settore.<\/p>\n<p>Il workshop affronta tematiche progettuali selezionate direttamente dall\u2019azienda, che spiega un brief e lascia gli studenti a seguire la propria creativit\u00e0.<\/p>\n<p>Durante l\u2019esperienza didattica, gli studenti possono mettere in pratica le proprie conoscenze, tirare fuori tutto il proprio potenziale, e possono soprattutto conoscere dettagliati cambi di progettazione.<\/p>\n<p>Dall\u20198 al 12 maggio sono stati organizzati diversi workshop per il corso di Design del Prodotto Industriale, in collaborazione con aziende di diversi campi di applicazione.<\/p>\n<p><em>SEZ. P1<\/em>\u2028Setsu &amp; Shinobu Ito con <strong>Manifattura Macchine Soffici <\/strong><\/p>\n<p><em>SEZ. P2<\/em>\u2028Raffaella Mangiarotti con <strong>Niteko <\/strong><\/p>\n<p><em>SEZ. P3<\/em>\u2028Terry Pecora\u2028con <strong>Ghelfi Ondulati<\/strong><\/p>\n<p><em>SEZ. P4<\/em>\u2028Shane Schneck &amp; Anna Barbara con <strong>Lancome<\/strong><\/p>\n<p><em>SEZ. P5\/I1<\/em>\u2028Emmanuel Gallina con <strong>Silent Gliss<\/strong><\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 100%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-964 gallery-columns-1 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1.jpg'><img decoding=\"async\" width=\"724\" height=\"1024\" data-src=\"https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1.jpg\" class=\"attachment-full size-full lazyload\" alt=\"workshop aziende\" data-srcset=\"https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1.jpg 724w, https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1-212x300.jpg 212w\" data-sizes=\"(max-width: 724px) 100vw, 724px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 724px; --smush-placeholder-aspect-ratio: 724\/1024;\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Il Politecnico di Milano offre grandi opportunit\u00e0 a studenti e aziende per conoscersi e creare piccoli momenti progettuali per accrescere le proprie esperienze. I workshop sono laboratori intensivi sviluppati all\u2019interno di una settimana, durante la quale da un lato le aziende selezionate hanno l\u2019opportunit\u00e0 di conoscere il potenziale dei giovani designer, dall\u2019altro gli studenti possono [&hellip;]<\/p>\n","protected":false},"featured_media":967,"template":"","categories":[9,8],"tags":[26,25,27],"class_list":["post-964","news","type-news","status-publish","has-post-thumbnail","hentry","category-laurea-magistrale","category-laurea-triennale","tag-integratedproductdesign","tag-polimi","tag-workshop"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Workshop come momenti di incontro tra studenti e aziende<\/title>\n<meta name=\"description\" content=\"I workshop presso il Politecnico sono grandi occasioni per lavorare direttamente a contatto con le aziende e accrescere la propria esperienza progettuale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Workshop come momenti di incontro tra studenti e aziende\" \/>\n<meta property=\"og:description\" content=\"I workshop presso il Politecnico sono grandi occasioni per lavorare direttamente a contatto con le aziende e accrescere la propria esperienza progettuale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/\" \/>\n<meta property=\"og:site_name\" content=\"BSc and MSc in Product Design\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-22T09:03:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/design-workshop-aziende\\\/\",\"url\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/design-workshop-aziende\\\/\",\"name\":\"Workshop come momenti di incontro tra studenti e aziende\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/design-workshop-aziende\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/design-workshop-aziende\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/productdesign.polimi.it\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/prodotto_maggio_2017-1.jpg\",\"datePublished\":\"2017-05-23T15:06:35+00:00\",\"dateModified\":\"2017-06-22T09:03:06+00:00\",\"description\":\"I workshop presso il Politecnico sono grandi occasioni per lavorare direttamente a contatto con le aziende e accrescere la propria esperienza progettuale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/design-workshop-aziende\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/design-workshop-aziende\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/design-workshop-aziende\\\/#primaryimage\",\"url\":\"https:\\\/\\\/productdesign.polimi.it\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/prodotto_maggio_2017-1.jpg\",\"contentUrl\":\"https:\\\/\\\/productdesign.polimi.it\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/prodotto_maggio_2017-1.jpg\",\"width\":724,\"height\":1024,\"caption\":\"workshop aziende\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/design-workshop-aziende\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Workshop come momenti di incontro tra studenti e aziende\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/\",\"name\":\"BSc and MSc in Product Design\",\"description\":\"Politecnico di Milano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/productdesign.polimi.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Workshop come momenti di incontro tra studenti e aziende","description":"I workshop presso il Politecnico sono grandi occasioni per lavorare direttamente a contatto con le aziende e accrescere la propria esperienza progettuale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/","og_locale":"it_IT","og_type":"article","og_title":"Workshop come momenti di incontro tra studenti e aziende","og_description":"I workshop presso il Politecnico sono grandi occasioni per lavorare direttamente a contatto con le aziende e accrescere la propria esperienza progettuale.","og_url":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/","og_site_name":"BSc and MSc in Product Design","article_modified_time":"2017-06-22T09:03:06+00:00","og_image":[{"width":724,"height":1024,"url":"https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/","url":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/","name":"Workshop come momenti di incontro tra studenti e aziende","isPartOf":{"@id":"https:\/\/productdesign.polimi.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/#primaryimage"},"image":{"@id":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/#primaryimage"},"thumbnailUrl":"https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1.jpg","datePublished":"2017-05-23T15:06:35+00:00","dateModified":"2017-06-22T09:03:06+00:00","description":"I workshop presso il Politecnico sono grandi occasioni per lavorare direttamente a contatto con le aziende e accrescere la propria esperienza progettuale.","breadcrumb":{"@id":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/#primaryimage","url":"https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1.jpg","contentUrl":"https:\/\/productdesign.polimi.it\/wp-content\/uploads\/2017\/05\/prodotto_maggio_2017-1.jpg","width":724,"height":1024,"caption":"workshop aziende"},{"@type":"BreadcrumbList","@id":"https:\/\/productdesign.polimi.it\/it\/news\/design-workshop-aziende\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/productdesign.polimi.it\/it\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/productdesign.polimi.it\/it\/news\/"},{"@type":"ListItem","position":3,"name":"Workshop come momenti di incontro tra studenti e aziende"}]},{"@type":"WebSite","@id":"https:\/\/productdesign.polimi.it\/it\/#website","url":"https:\/\/productdesign.polimi.it\/it\/","name":"BSc and MSc in Product Design","description":"Politecnico di Milano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/productdesign.polimi.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/news\/964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":3,"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/news\/964\/revisions"}],"predecessor-version":[{"id":1076,"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/news\/964\/revisions\/1076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/media\/967"}],"wp:attachment":[{"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/media?parent=964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/categories?post=964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/productdesign.polimi.it\/it\/wp-json\/wp\/v2\/tags?post=964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}